{"id":4354,"date":"2022-06-30T16:27:18","date_gmt":"2022-06-30T20:27:18","guid":{"rendered":"https:\/\/serviceexpress.com\/eol-eosl-database\/eol-database\/cisco-air-cap2602i-s-k9-cisco-network-services\/"},"modified":"2025-12-29T09:33:56","modified_gmt":"2025-12-29T14:33:56","slug":"cisco-air-cap2602i-s-k9-cisco-network-services","status":"publish","type":"eol-database","link":"https:\/\/serviceexpress.com\/eol-eosl-database\/products\/cisco-air-cap2602i-s-k9-cisco-network-services\/","title":{"rendered":"CISCO AIRONET 2620I WIRELESS ACESS POINT"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":32,"featured_media":30315,"template":"","manufacturer":[28],"product-category":[8],"support-status":[4],"class_list":["post-4354","eol-database","type-eol-database","status-publish","has-post-thumbnail","hentry","manufacturer-cisco","product-category-network","support-status-supported"],"featured_image_src":"https:\/\/serviceexpress.com\/eol-eosl-database\/wp-content\/uploads\/sites\/4\/2022\/04\/EOL-EOSL-meta.jpg","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>CISCO AIRONET 2620I WIRELESS ACESS POINT AIR-CAP2602I-S-K9 EOL &amp; EOSL Dates<\/title>\n<meta name=\"description\" content=\"View End of Life (EOL) &amp; End of Service Life (EOSL) dates for CISCO AIRONET 2620I WIRELESS ACESS POINT AIR-CAP2602I-S-K9 hardware. Search our database for more.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/serviceexpress.com\/eol-eosl-database\/products\/cisco-air-cap2602i-s-k9-cisco-network-services\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CISCO AIRONET 2620I WIRELESS ACESS POINT AIR-CAP2602I-S-K9 EOL &amp; EOSL Dates\" \/>\n<meta property=\"og:description\" content=\"View End of Life (EOL) &amp; End of Service Life (EOSL) dates for CISCO AIRONET 2620I WIRELESS ACESS POINT AIR-CAP2602I-S-K9 hardware. Search our database for more.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/serviceexpress.com\/eol-eosl-database\/products\/cisco-air-cap2602i-s-k9-cisco-network-services\/\" \/>\n<meta property=\"og:site_name\" content=\"Service Express EOL &amp; EOSL Database\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/weareserviceexpress\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-29T14:33:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/serviceexpress.com\/eol-eosl-database\/wp-content\/uploads\/sites\/4\/2022\/04\/EOL-EOSL-meta.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"405\" \/>\n\t<meta property=\"og:image:height\" content=\"212\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"CISCO AIRONET 2620I WIRELESS ACESS POINT AIR-CAP2602I-S-K9 EOL &amp; EOSL Dates\" \/>\n<meta name=\"twitter:description\" content=\"View End of Life (EOL) &amp; End of Service Life (EOSL) dates for CISCO AIRONET 2620I WIRELESS ACESS POINT AIR-CAP2602I-S-K9 hardware. Search our database for more.\" \/>\n<meta name=\"twitter:site\" content=\"@ServiceExpress\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"SearchResultsPage\"],\"@id\":\"https:\\\/\\\/serviceexpress.com\\\/eol-eosl-database\\\/products\\\/cisco-air-cap2602i-s-k9-cisco-network-services\\\/\",\"url\":\"https:\\\/\\\/serviceexpress.com\\\/eol-eosl-database\\\/products\\\/cisco-air-cap2602i-s-k9-cisco-network-services\\\/\",\"name\":\"CISCO AIRONET 2620I WIRELESS ACESS POINT AIR-CAP2602I-S-K9 EOL & EOSL Dates\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/serviceexpress.com\\\/eol-eosl-database\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/serviceexpress.com\\\/eol-eosl-database\\\/products\\\/cisco-air-cap2602i-s-k9-cisco-network-services\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/serviceexpress.com\\\/eol-eosl-database\\\/products\\\/cisco-air-cap2602i-s-k9-cisco-network-services\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/serviceexpress.com\\\/eol-eosl-database\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/04\\\/EOL-EOSL-meta.jpg\",\"datePublished\":\"2022-06-30T20:27:18+00:00\",\"dateModified\":\"2025-12-29T14:33:56+00:00\",\"description\":\"View End of Life (EOL) & End of Service Life (EOSL) dates for CISCO AIRONET 2620I WIRELESS ACESS POINT AIR-CAP2602I-S-K9 hardware. Search our database for more.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/serviceexpress.com\\\/eol-eosl-database\\\/products\\\/cisco-air-cap2602i-s-k9-cisco-network-services\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/serviceexpress.com\\\/eol-eosl-database\\\/products\\\/cisco-air-cap2602i-s-k9-cisco-network-services\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/serviceexpress.com\\\/eol-eosl-database\\\/products\\\/cisco-air-cap2602i-s-k9-cisco-network-services\\\/#primaryimage\",\"url\":\"https:\\\/\\\/serviceexpress.com\\\/eol-eosl-database\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/04\\\/EOL-EOSL-meta.jpg\",\"contentUrl\":\"https:\\\/\\\/serviceexpress.com\\\/eol-eosl-database\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/04\\\/EOL-EOSL-meta.jpg\",\"width\":405,\"height\":212},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/serviceexpress.com\\\/eol-eosl-database\\\/products\\\/cisco-air-cap2602i-s-k9-cisco-network-services\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/serviceexpress.com\\\/eol-eosl-database\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CISCO AIRONET 2620I WIRELESS ACESS POINT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/serviceexpress.com\\\/eol-eosl-database\\\/#website\",\"url\":\"https:\\\/\\\/serviceexpress.com\\\/eol-eosl-database\\\/\",\"name\":\"Service Express EOL &amp; EOSL Database\",\"description\":\"Global Data Center Solutions &amp; Support\",\"publisher\":{\"@id\":\"https:\\\/\\\/serviceexpress.com\\\/eol-eosl-database\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/serviceexpress.com\\\/eol-eosl-database\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/serviceexpress.com\\\/eol-eosl-database\\\/#organization\",\"name\":\"Service Express EOL &amp; EOSL Database\",\"url\":\"https:\\\/\\\/serviceexpress.com\\\/eol-eosl-database\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/serviceexpress.com\\\/eol-eosl-database\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/serviceexpress.com\\\/eol-eosl-database\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/01\\\/service-express-meta.jpg\",\"contentUrl\":\"https:\\\/\\\/serviceexpress.com\\\/eol-eosl-database\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/01\\\/service-express-meta.jpg\",\"width\":1200,\"height\":628,\"caption\":\"Service Express EOL &amp; EOSL Database\"},\"image\":{\"@id\":\"https:\\\/\\\/serviceexpress.com\\\/eol-eosl-database\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/weareserviceexpress\\\/\",\"https:\\\/\\\/x.com\\\/ServiceExpress\",\"https:\\\/\\\/www.instagram.com\\\/serviceexpress\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/service-express-inc\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCa1MO2iHOytlWx_xCX9uoug\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"CISCO AIRONET 2620I WIRELESS ACESS POINT AIR-CAP2602I-S-K9 EOL & EOSL Dates","description":"View End of Life (EOL) & End of Service Life (EOSL) dates for CISCO AIRONET 2620I WIRELESS ACESS POINT AIR-CAP2602I-S-K9 hardware. Search our database for more.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/serviceexpress.com\/eol-eosl-database\/products\/cisco-air-cap2602i-s-k9-cisco-network-services\/","og_locale":"en_US","og_type":"article","og_title":"CISCO AIRONET 2620I WIRELESS ACESS POINT AIR-CAP2602I-S-K9 EOL & EOSL Dates","og_description":"View End of Life (EOL) & End of Service Life (EOSL) dates for CISCO AIRONET 2620I WIRELESS ACESS POINT AIR-CAP2602I-S-K9 hardware. Search our database for more.","og_url":"https:\/\/serviceexpress.com\/eol-eosl-database\/products\/cisco-air-cap2602i-s-k9-cisco-network-services\/","og_site_name":"Service Express EOL &amp; EOSL Database","article_publisher":"https:\/\/www.facebook.com\/weareserviceexpress\/","article_modified_time":"2025-12-29T14:33:56+00:00","og_image":[{"width":405,"height":212,"url":"https:\/\/serviceexpress.com\/eol-eosl-database\/wp-content\/uploads\/sites\/4\/2022\/04\/EOL-EOSL-meta.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"CISCO AIRONET 2620I WIRELESS ACESS POINT AIR-CAP2602I-S-K9 EOL & EOSL Dates","twitter_description":"View End of Life (EOL) & End of Service Life (EOSL) dates for CISCO AIRONET 2620I WIRELESS ACESS POINT AIR-CAP2602I-S-K9 hardware. Search our database for more.","twitter_site":"@ServiceExpress","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","SearchResultsPage"],"@id":"https:\/\/serviceexpress.com\/eol-eosl-database\/products\/cisco-air-cap2602i-s-k9-cisco-network-services\/","url":"https:\/\/serviceexpress.com\/eol-eosl-database\/products\/cisco-air-cap2602i-s-k9-cisco-network-services\/","name":"CISCO AIRONET 2620I WIRELESS ACESS POINT AIR-CAP2602I-S-K9 EOL & EOSL Dates","isPartOf":{"@id":"https:\/\/serviceexpress.com\/eol-eosl-database\/#website"},"primaryImageOfPage":{"@id":"https:\/\/serviceexpress.com\/eol-eosl-database\/products\/cisco-air-cap2602i-s-k9-cisco-network-services\/#primaryimage"},"image":{"@id":"https:\/\/serviceexpress.com\/eol-eosl-database\/products\/cisco-air-cap2602i-s-k9-cisco-network-services\/#primaryimage"},"thumbnailUrl":"https:\/\/serviceexpress.com\/eol-eosl-database\/wp-content\/uploads\/sites\/4\/2022\/04\/EOL-EOSL-meta.jpg","datePublished":"2022-06-30T20:27:18+00:00","dateModified":"2025-12-29T14:33:56+00:00","description":"View End of Life (EOL) & End of Service Life (EOSL) dates for CISCO AIRONET 2620I WIRELESS ACESS POINT AIR-CAP2602I-S-K9 hardware. Search our database for more.","breadcrumb":{"@id":"https:\/\/serviceexpress.com\/eol-eosl-database\/products\/cisco-air-cap2602i-s-k9-cisco-network-services\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/serviceexpress.com\/eol-eosl-database\/products\/cisco-air-cap2602i-s-k9-cisco-network-services\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/serviceexpress.com\/eol-eosl-database\/products\/cisco-air-cap2602i-s-k9-cisco-network-services\/#primaryimage","url":"https:\/\/serviceexpress.com\/eol-eosl-database\/wp-content\/uploads\/sites\/4\/2022\/04\/EOL-EOSL-meta.jpg","contentUrl":"https:\/\/serviceexpress.com\/eol-eosl-database\/wp-content\/uploads\/sites\/4\/2022\/04\/EOL-EOSL-meta.jpg","width":405,"height":212},{"@type":"BreadcrumbList","@id":"https:\/\/serviceexpress.com\/eol-eosl-database\/products\/cisco-air-cap2602i-s-k9-cisco-network-services\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/serviceexpress.com\/eol-eosl-database\/"},{"@type":"ListItem","position":2,"name":"CISCO AIRONET 2620I WIRELESS ACESS POINT"}]},{"@type":"WebSite","@id":"https:\/\/serviceexpress.com\/eol-eosl-database\/#website","url":"https:\/\/serviceexpress.com\/eol-eosl-database\/","name":"Service Express EOL &amp; EOSL Database","description":"Global Data Center Solutions &amp; Support","publisher":{"@id":"https:\/\/serviceexpress.com\/eol-eosl-database\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/serviceexpress.com\/eol-eosl-database\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/serviceexpress.com\/eol-eosl-database\/#organization","name":"Service Express EOL &amp; EOSL Database","url":"https:\/\/serviceexpress.com\/eol-eosl-database\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/serviceexpress.com\/eol-eosl-database\/#\/schema\/logo\/image\/","url":"https:\/\/serviceexpress.com\/eol-eosl-database\/wp-content\/uploads\/sites\/4\/2022\/01\/service-express-meta.jpg","contentUrl":"https:\/\/serviceexpress.com\/eol-eosl-database\/wp-content\/uploads\/sites\/4\/2022\/01\/service-express-meta.jpg","width":1200,"height":628,"caption":"Service Express EOL &amp; EOSL Database"},"image":{"@id":"https:\/\/serviceexpress.com\/eol-eosl-database\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/weareserviceexpress\/","https:\/\/x.com\/ServiceExpress","https:\/\/www.instagram.com\/serviceexpress\/","https:\/\/www.linkedin.com\/company\/service-express-inc\/","https:\/\/www.youtube.com\/channel\/UCa1MO2iHOytlWx_xCX9uoug"]}]}},"_links":{"self":[{"href":"https:\/\/serviceexpress.com\/eol-eosl-database\/wp-json\/wp\/v2\/eol-database\/4354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serviceexpress.com\/eol-eosl-database\/wp-json\/wp\/v2\/eol-database"}],"about":[{"href":"https:\/\/serviceexpress.com\/eol-eosl-database\/wp-json\/wp\/v2\/types\/eol-database"}],"author":[{"embeddable":true,"href":"https:\/\/serviceexpress.com\/eol-eosl-database\/wp-json\/wp\/v2\/users\/32"}],"version-history":[{"count":0,"href":"https:\/\/serviceexpress.com\/eol-eosl-database\/wp-json\/wp\/v2\/eol-database\/4354\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/serviceexpress.com\/eol-eosl-database\/wp-json\/wp\/v2\/media\/30315"}],"wp:attachment":[{"href":"https:\/\/serviceexpress.com\/eol-eosl-database\/wp-json\/wp\/v2\/media?parent=4354"}],"wp:term":[{"taxonomy":"manufacturer","embeddable":true,"href":"https:\/\/serviceexpress.com\/eol-eosl-database\/wp-json\/wp\/v2\/manufacturer?post=4354"},{"taxonomy":"product-category","embeddable":true,"href":"https:\/\/serviceexpress.com\/eol-eosl-database\/wp-json\/wp\/v2\/product-category?post=4354"},{"taxonomy":"support-status","embeddable":true,"href":"https:\/\/serviceexpress.com\/eol-eosl-database\/wp-json\/wp\/v2\/support-status?post=4354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}